{"id":2911,"date":"2022-10-13T09:49:29","date_gmt":"2022-10-13T07:49:29","guid":{"rendered":"https:\/\/masseriaderchia.it\/camera-e-suite\/king-room-la-corte\/"},"modified":"2022-10-13T09:49:29","modified_gmt":"2022-10-13T07:49:29","slug":"king-room-la-corte","status":"publish","type":"camere-e-suite","link":"https:\/\/masseriaderchia.it\/de\/camera-e-suite\/king-room-la-corte\/","title":{"rendered":"King Room LA CORTE"},"featured_media":2912,"parent":0,"template":"","class_list":["post-2911","camere-e-suite","type-camere-e-suite","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>King Room LA CORTE &#8212; Masseria D&#039;Erchia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/masseriaderchia.it\/camera-e-suite\/king-room-la-corte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"King Room LA CORTE &#8212; Masseria D&#039;Erchia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/masseriaderchia.it\/camera-e-suite\/king-room-la-corte\/\" \/>\n<meta property=\"og:site_name\" content=\"Masseria D&#039;Erchia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/masseriaderchia\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/masseriaderchia.it\\\/camera-e-suite\\\/king-room-la-corte\\\/\",\"url\":\"https:\\\/\\\/masseriaderchia.it\\\/camera-e-suite\\\/king-room-la-corte\\\/\",\"name\":\"King Room LA CORTE &#8212; Masseria D&#039;Erchia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/masseriaderchia.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/masseriaderchia.it\\\/camera-e-suite\\\/king-room-la-corte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/masseriaderchia.it\\\/camera-e-suite\\\/king-room-la-corte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/masseriaderchia.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/masseria-1.jpg\",\"datePublished\":\"2022-10-13T07:49:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/masseriaderchia.it\\\/camera-e-suite\\\/king-room-la-corte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/masseriaderchia.it\\\/camera-e-suite\\\/king-room-la-corte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/masseriaderchia.it\\\/camera-e-suite\\\/king-room-la-corte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/masseriaderchia.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/masseria-1.jpg\",\"contentUrl\":\"https:\\\/\\\/masseriaderchia.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/masseria-1.jpg\",\"width\":1620,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/masseriaderchia.it\\\/camera-e-suite\\\/king-room-la-corte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/masseriaderchia.it\\\/de\\\/hauptseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camere e Suite\",\"item\":\"https:\\\/\\\/masseriaderchia.it\\\/camera-e-suite\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"King Room LA CORTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/masseriaderchia.it\\\/#website\",\"url\":\"https:\\\/\\\/masseriaderchia.it\\\/\",\"name\":\"Masseria D&#039;Erchia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/masseriaderchia.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/masseriaderchia.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/masseriaderchia.it\\\/#organization\",\"name\":\"Masseria D'Erchia\",\"url\":\"https:\\\/\\\/masseriaderchia.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/masseriaderchia.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/masseriaderchia.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_nuovo.png\",\"contentUrl\":\"https:\\\/\\\/masseriaderchia.it\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/logo_nuovo.png\",\"width\":117,\"height\":124,\"caption\":\"Masseria D'Erchia\"},\"image\":{\"@id\":\"https:\\\/\\\/masseriaderchia.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/masseriaderchia\\\/\",\"https:\\\/\\\/www.instagram.com\\\/masseriaderchia\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"King Room LA CORTE &#8212; Masseria D&#039;Erchia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/masseriaderchia.it\/camera-e-suite\/king-room-la-corte\/","og_locale":"de_DE","og_type":"article","og_title":"King Room LA CORTE &#8212; Masseria D&#039;Erchia","og_url":"https:\/\/masseriaderchia.it\/camera-e-suite\/king-room-la-corte\/","og_site_name":"Masseria D&#039;Erchia","article_publisher":"https:\/\/www.facebook.com\/masseriaderchia\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/masseriaderchia.it\/camera-e-suite\/king-room-la-corte\/","url":"https:\/\/masseriaderchia.it\/camera-e-suite\/king-room-la-corte\/","name":"King Room LA CORTE &#8212; Masseria D&#039;Erchia","isPartOf":{"@id":"https:\/\/masseriaderchia.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/masseriaderchia.it\/camera-e-suite\/king-room-la-corte\/#primaryimage"},"image":{"@id":"https:\/\/masseriaderchia.it\/camera-e-suite\/king-room-la-corte\/#primaryimage"},"thumbnailUrl":"https:\/\/masseriaderchia.it\/wp-content\/uploads\/2022\/10\/masseria-1.jpg","datePublished":"2022-10-13T07:49:29+00:00","breadcrumb":{"@id":"https:\/\/masseriaderchia.it\/camera-e-suite\/king-room-la-corte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/masseriaderchia.it\/camera-e-suite\/king-room-la-corte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/masseriaderchia.it\/camera-e-suite\/king-room-la-corte\/#primaryimage","url":"https:\/\/masseriaderchia.it\/wp-content\/uploads\/2022\/10\/masseria-1.jpg","contentUrl":"https:\/\/masseriaderchia.it\/wp-content\/uploads\/2022\/10\/masseria-1.jpg","width":1620,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/masseriaderchia.it\/camera-e-suite\/king-room-la-corte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/masseriaderchia.it\/de\/hauptseite\/"},{"@type":"ListItem","position":2,"name":"Camere e Suite","item":"https:\/\/masseriaderchia.it\/camera-e-suite\/"},{"@type":"ListItem","position":3,"name":"King Room LA CORTE"}]},{"@type":"WebSite","@id":"https:\/\/masseriaderchia.it\/#website","url":"https:\/\/masseriaderchia.it\/","name":"Masseria D&#039;Erchia","description":"","publisher":{"@id":"https:\/\/masseriaderchia.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/masseriaderchia.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/masseriaderchia.it\/#organization","name":"Masseria D'Erchia","url":"https:\/\/masseriaderchia.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/masseriaderchia.it\/#\/schema\/logo\/image\/","url":"https:\/\/masseriaderchia.it\/wp-content\/uploads\/2022\/10\/logo_nuovo.png","contentUrl":"https:\/\/masseriaderchia.it\/wp-content\/uploads\/2022\/10\/logo_nuovo.png","width":117,"height":124,"caption":"Masseria D'Erchia"},"image":{"@id":"https:\/\/masseriaderchia.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/masseriaderchia\/","https:\/\/www.instagram.com\/masseriaderchia\/"]}]}},"_links":{"self":[{"href":"https:\/\/masseriaderchia.it\/de\/wp-json\/wp\/v2\/camere-e-suite\/2911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masseriaderchia.it\/de\/wp-json\/wp\/v2\/camere-e-suite"}],"about":[{"href":"https:\/\/masseriaderchia.it\/de\/wp-json\/wp\/v2\/types\/camere-e-suite"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/masseriaderchia.it\/de\/wp-json\/wp\/v2\/media\/2912"}],"wp:attachment":[{"href":"https:\/\/masseriaderchia.it\/de\/wp-json\/wp\/v2\/media?parent=2911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}